{"id":56211,"date":"2026-04-28T20:19:51","date_gmt":"2026-04-28T20:19:51","guid":{"rendered":"https:\/\/dev.deltamed.cl\/?post_type=product&#038;p=56211"},"modified":"2026-08-03T14:00:07","modified_gmt":"2026-08-03T18:00:07","slug":"silla-de-tina-fija","status":"publish","type":"product","link":"https:\/\/deltamed.cl\/tienda\/producto\/silla-de-tina-fija\/","title":{"rendered":"Silla de tina fija"},"content":{"rendered":"<p>Silla de tina fija<\/p>\n<p>Asiento para ducha\/tina desmontable en dos piezas para facilitar su transporte, con 4 posiciones diferentes<\/p>\n<p>para la comodidad del usuario.<\/p>\n<p>CARACTERISTICAS:<\/p>\n<p>\u2022 Estructura tubular en aluminio anodizado.<\/p>\n<p>\u2022 Asiento de pl\u00e1stico desmontable con perforaci\u00f3n de alta resistencia.<\/p>\n<p>\u2022 Respaldo desmontable para mayor comodidad con perforaci\u00f3n.<\/p>\n<p>\u2022 Posiciones regulables de f\u00e1cil ajuste:<\/p>\n<p>o Medio de fijaci\u00f3n mediante palanca de seguro en cualquier posici\u00f3n.<\/p>\n<p>o Manipulable sin uso de herramientas.<\/p>\n<p>\u2022 Asas de seguridad y reposabrazos.<\/p>\n<p>\u2022 Impermeable.<\/p>\n<p>\u2022 Cuenta con manual de uso.<\/p>\n<p>ESPECIFICACIONES T\u00c9CNICAS:<\/p>\n<p>Medidas:<\/p>\n<ul>\n<li>Ancho total 72 cm<\/li>\n<li>Ancho asiento 50 cm<\/li>\n<li>Fondo total 52 cm<\/li>\n<li>Fondo asiento 52 cm<\/li>\n<li>Peso m\u00e1ximo de usuario 120 kg<\/li>\n<li>Peso total 3.8 kg<\/li>\n<li>Altura Total 53 cm<\/li>\n<li>Altura reposabrazos 19 cm<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Silla de tina fija<\/p>\n<p>Asiento para ducha\/tina desmontable en dos piezas para facilitar su transporte, con 4 posiciones diferentes<\/p>\n<p>para la comodidad del usuario.<\/p>\n<p>CARACTERISTICAS:<\/p>\n<p>\u2022 Estructura tubular en aluminio anodizado.<\/p>\n<p>\u2022 Asiento de pl\u00e1stico desmontable con perforaci\u00f3n de alta resistencia.<\/p>\n<p>\u2022 Respaldo desmontable para mayor comodidad con perforaci\u00f3n.<\/p>\n<p>\u2022 Posiciones regulables de f\u00e1cil ajuste:<\/p>\n<p>o Medio de fijaci\u00f3n mediante palanca de seguro en cualquier posici\u00f3n.<\/p>\n<p>o Manipulable sin uso de herramientas.<\/p>\n<p>\u2022 Asas de seguridad y reposabrazos.<\/p>\n<p>\u2022 Impermeable.<\/p>\n<p>\u2022 Cuenta con manual de uso.<\/p>\n","protected":false},"featured_media":12811,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[6095],"product_cat":[6369,6370],"product_tag":[5297,5339,6070,5596],"class_list":["post-56211","product","type-product","status-publish","has-post-thumbnail","product_brand-caremax","product_cat-articulos-de-banos","product_cat-sillas-de-bano","product_tag-baston","product_tag-burrito","product_tag-lifante","product_tag-silla-de-ruedas","first","outofstock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"_links":{"self":[{"href":"https:\/\/deltamed.cl\/tienda\/wp-json\/wp\/v2\/product\/56211","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/deltamed.cl\/tienda\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/deltamed.cl\/tienda\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/deltamed.cl\/tienda\/wp-json\/wp\/v2\/comments?post=56211"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/deltamed.cl\/tienda\/wp-json\/wp\/v2\/media\/12811"}],"wp:attachment":[{"href":"https:\/\/deltamed.cl\/tienda\/wp-json\/wp\/v2\/media?parent=56211"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/deltamed.cl\/tienda\/wp-json\/wp\/v2\/product_brand?post=56211"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/deltamed.cl\/tienda\/wp-json\/wp\/v2\/product_cat?post=56211"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/deltamed.cl\/tienda\/wp-json\/wp\/v2\/product_tag?post=56211"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}