{"id":55862,"date":"2026-04-28T20:15:29","date_gmt":"2026-04-28T20:15:29","guid":{"rendered":"https:\/\/dev.deltamed.cl\/?post_type=product&#038;p=55862"},"modified":"2026-05-19T20:55:28","modified_gmt":"2026-05-19T20:55:28","slug":"urgotul-ag-silver-10x12cm","status":"publish","type":"product","link":"https:\/\/deltamed.cl\/tienda\/producto\/urgotul-ag-silver-10x12cm\/","title":{"rendered":"UrgoTul Ag\/Silver 10X12cm"},"content":{"rendered":"<p>UrgoTul Ag\/Silver 10X12cm<\/p>\n<p>1 unidad<\/p>\n<p>UrgoTul Ag, es una malla antimicrobiana no oclusiva y flexible de poli\u00e9ster recubierta con part\u00edculas de hidrocoloide, componentes lip\u00eddicos y sales de plata (TLC-Ag).<\/p>\n<p>En contacto con el exudado, las part\u00edculas hidrocoloides se gelifican e interact\u00faan con las part\u00edculas lip\u00eddicas de UrgoTul Ag, formando un gel que crea un ambiente h\u00famedo favorable para el proceso de cicatrizaci\u00f3n. UrgoTul Ag estimula la proliferaci\u00f3n de fibroblastos, c\u00e9lulas clave en la cicatrizaci\u00f3n. Adem\u00e1s, en contacto con el exudado, libera progresivamente los iones plata, lo que confiere al ap\u00f3sito una actividad antibacteriana de contacto capaz de disminuir la carga bacteriana local. El ap\u00f3sito ha demostrado actividad antibacteriana in-vitro de hasta 7 d\u00edas y contribuye a reducir el olor causado por los microorganismos presentes en la herida.<\/p>\n<p><strong>Propiedades<\/strong><\/p>\n<p>La tecnolog\u00eda de UrgoTul Ag da como resultado propiedades espec\u00edficas:<\/p>\n<p>Mantenimiento de un elevado nivel de recubrimiento lip\u00eddico a lo largo del tiempo.<\/p>\n<p>Retirada atraum\u00e1tica para los tejidos neoformados.<\/p>\n<p>Cambio de ap\u00f3sito indoloro para el paciente.<\/p>\n<p>Actividad antibacteriana de contacto capaz de disminuir la carga bacteriana local.<\/p>\n<p><strong>Mecanismo de acci\u00f3n<\/strong><\/p>\n<p>UrgoTul Ag crea un ambiente h\u00famedo favorable para el proceso de cicatrizaci\u00f3n, estimulando la proliferaci\u00f3n de fibroblastos. Su composici\u00f3n, que incluye componentes lip\u00eddicos, no es grasienta al tacto y evita que se adhiera a la herida o a la zona circundante, lo que hace que los cambios de ap\u00f3sito sean indoloros y atraum\u00e1ticos. Adem\u00e1s, libera iones de plata que ofrecen una actividad antibacteriana capaz de reducir la carga bacteriana local y el olor de la herida.<\/p>\n<p><strong>Indicaciones<\/strong><\/p>\n<p>UrgoTul Ag est\u00e1 indicado para el tratamiento de heridas cr\u00f3nicas (\u00falceras venosas, \u00falceras por presi\u00f3n, etc.) y agudas (quemaduras de segundo grado, dermoabrasiones, heridas traum\u00e1ticas, heridas postoperatorias, etc.) con bajo exudado y signos o riesgos de infecci\u00f3n local.<\/p>\n<p><strong>Contraindicaciones<\/strong><\/p>\n<p>No usar en caso de sensibilidad conocida a la plata o a otros componentes del ap\u00f3sito.<\/p>\n<p>No dejar el ap\u00f3sito puesto durante un examen IRM.<\/p>\n<p><strong>Modo de uso<\/strong><\/p>\n<p>Limpiar la herida con soluci\u00f3n salina normal.<\/p>\n<p>Aplicar UrgoTul Ag directamente sobre la herida.<\/p>\n<p>Cubrir UrgoTul Ag con un ap\u00f3sito secundario y asegurarlo con un vendaje de fijaci\u00f3n.<\/p>\n<p>El cambio de ap\u00f3sito puede realizarse cada 1 a 3 d\u00edas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>UrgoTul Ag\/Silver 10X12cm<\/p>\n<p>1 unidad<\/p>\n<p>UrgoTul Ag, es una malla antimicrobiana no oclusiva y flexible de poli\u00e9ster recubierta con part\u00edculas de hidrocoloide, componentes lip\u00eddicos y sales de plata (TLC-Ag).<\/p>\n<p>En contacto con el exudado, las part\u00edculas hidrocoloides se gelifican e interact\u00faan con las part\u00edculas lip\u00eddicas de UrgoTul Ag, formando un gel que crea un ambiente h\u00famedo favorable para el proceso de cicatrizaci\u00f3n. UrgoTul Ag estimula la proliferaci\u00f3n de fibroblastos, c\u00e9lulas clave en la cicatrizaci\u00f3n. Adem\u00e1s, en contacto con el exudado, libera progresivamente los iones plata, lo que confiere al ap\u00f3sito una actividad antibacteriana de contacto capaz de disminuir la carga bacteriana local. El ap\u00f3sito ha demostrado actividad antibacteriana in-vitro de hasta 7 d\u00edas y contribuye a reducir el olor causado por los microorganismos presentes en la herida.<\/p>\n","protected":false},"featured_media":12120,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[6043],"product_cat":[6409,6408],"product_tag":[6046,6679,6047,6678,5345],"class_list":["post-55862","product","type-product","status-publish","has-post-thumbnail","product_brand-urgo","product_cat-apositos","product_cat-tratamiento-de-heridas","product_tag-enfermeria","product_tag-kinesiologo","product_tag-medicina","product_tag-regalo","product_tag-tens","first","outofstock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"_links":{"self":[{"href":"https:\/\/deltamed.cl\/tienda\/wp-json\/wp\/v2\/product\/55862","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/deltamed.cl\/tienda\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/deltamed.cl\/tienda\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/deltamed.cl\/tienda\/wp-json\/wp\/v2\/comments?post=55862"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/deltamed.cl\/tienda\/wp-json\/wp\/v2\/media\/12120"}],"wp:attachment":[{"href":"https:\/\/deltamed.cl\/tienda\/wp-json\/wp\/v2\/media?parent=55862"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/deltamed.cl\/tienda\/wp-json\/wp\/v2\/product_brand?post=55862"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/deltamed.cl\/tienda\/wp-json\/wp\/v2\/product_cat?post=55862"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/deltamed.cl\/tienda\/wp-json\/wp\/v2\/product_tag?post=55862"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}